{"id":3404,"date":"2026-05-21T13:37:31","date_gmt":"2026-05-21T11:37:31","guid":{"rendered":"https:\/\/www.costmasters.com\/?p=3404"},"modified":"2026-05-21T13:37:32","modified_gmt":"2026-05-21T11:37:32","slug":"la-synthese-de-la-taxe-sur-les-plus-values-en-une-page","status":"publish","type":"post","link":"https:\/\/www.costmasters.com\/en\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/","title":{"rendered":"La synth\u00e8se de la taxe sur les plus-values, en une page"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Il n\u2019y a plus de doute, l\u2019Etat belge taxe d\u00e9sormais les plus-values financi\u00e8res, sous r\u00e9serve des recours introduits contre la loi du 6 avril dernier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les principes et modalit\u00e9s semblent limpides pour les plus-values sur actions cot\u00e9es. <strong>Mais il n\u2019en va pas de m\u00eame pour les participations substantielles des actionnaires et dirigeants de PME. <\/strong>C\u2019est donc \u00e0 leur intention que nous avons r\u00e9sum\u00e9 et illustr\u00e9 la loi en une page, comme ci-dessous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous pensez \u00eatre concern\u00e9 par cette taxe et souhaitez en parler, n&rsquo;h\u00e9sitez pas : contactez-nous. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"gb-block-image gb-block-image-c721ebe5\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1707\" height=\"2560\" class=\"gb-image gb-image-c721ebe5\" src=\"https:\/\/www.costmasters.com\/wp-content\/uploads\/2026\/05\/costmasters_plusvalues_final-scaled.jpg\" alt=\"\" title=\"costmasters_plusvalues_final\" srcset=\"https:\/\/www.costmasters.com\/wp-content\/uploads\/2026\/05\/costmasters_plusvalues_final-scaled.jpg 1707w, https:\/\/www.costmasters.com\/wp-content\/uploads\/2026\/05\/costmasters_plusvalues_final-200x300.jpg 200w, https:\/\/www.costmasters.com\/wp-content\/uploads\/2026\/05\/costmasters_plusvalues_final-683x1024.jpg 683w, https:\/\/www.costmasters.com\/wp-content\/uploads\/2026\/05\/costmasters_plusvalues_final-768x1152.jpg 768w, https:\/\/www.costmasters.com\/wp-content\/uploads\/2026\/05\/costmasters_plusvalues_final-1024x1536.jpg 1024w, https:\/\/www.costmasters.com\/wp-content\/uploads\/2026\/05\/costmasters_plusvalues_final-1365x2048.jpg 1365w, https:\/\/www.costmasters.com\/wp-content\/uploads\/2026\/05\/costmasters_plusvalues_final-8x12.jpg 8w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Il n\u2019y a plus de doute, l\u2019Etat belge taxe d\u00e9sormais les plus-values financi\u00e8res, sous r\u00e9serve des recours introduits contre la loi du 6 avril dernier. Les principes et modalit\u00e9s semblent limpides pour les plus-values sur actions cot\u00e9es. Mais il n\u2019en va pas de m\u00eame pour les participations substantielles des actionnaires et dirigeants de PME. C\u2019est &#8230; <a title=\"La synth\u00e8se de la taxe sur les plus-values, en une page\" class=\"read-more\" href=\"https:\/\/www.costmasters.com\/en\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/\" aria-label=\"More on La synth\u00e8se de la taxe sur les plus-values, en une page\">Read more<\/a><\/p>","protected":false},"author":7,"featured_media":3097,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[13],"class_list":["post-3404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-fiscalite","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La synth\u00e8se de la taxe sur les plus-values, en une page - Costmasters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.costmasters.com\/en\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La synth\u00e8se de la taxe sur les plus-values, en une page - Costmasters\" \/>\n<meta property=\"og:description\" content=\"Il n\u2019y a plus de doute, l\u2019Etat belge taxe d\u00e9sormais les plus-values financi\u00e8res, sous r\u00e9serve des recours introduits contre la loi du 6 avril dernier. Les principes et modalit\u00e9s semblent limpides pour les plus-values sur actions cot\u00e9es. Mais il n\u2019en va pas de m\u00eame pour les participations substantielles des actionnaires et dirigeants de PME. C\u2019est ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.costmasters.com\/en\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/\" \/>\n<meta property=\"og:site_name\" content=\"Costmasters\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-21T11:37:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-21T11:37:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costmasters.com\/wp-content\/uploads\/2023\/04\/billets-reduit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"452\" \/>\n\t<meta property=\"og:image:height\" content=\"362\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charles Markowicz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles Markowicz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/\"},\"author\":{\"name\":\"Charles Markowicz\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#\\\/schema\\\/person\\\/3cf1b4cd7352824684853dac4ed7d30a\"},\"headline\":\"La synth\u00e8se de la taxe sur les plus-values, en une page\",\"datePublished\":\"2026-05-21T11:37:31+00:00\",\"dateModified\":\"2026-05-21T11:37:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/\"},\"wordCount\":109,\"publisher\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costmasters.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/billets-reduit.jpg\",\"keywords\":[\"Fiscalit\u00e9\"],\"articleSection\":[\"Article\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/\",\"url\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/\",\"name\":\"La synth\u00e8se de la taxe sur les plus-values, en une page - Costmasters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.costmasters.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/billets-reduit.jpg\",\"datePublished\":\"2026-05-21T11:37:31+00:00\",\"dateModified\":\"2026-05-21T11:37:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.costmasters.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/billets-reduit.jpg\",\"contentUrl\":\"https:\\\/\\\/www.costmasters.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/billets-reduit.jpg\",\"width\":452,\"height\":362,\"caption\":\"d\u00e9penser moins - Shutterstock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.costmasters.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La synth\u00e8se de la taxe sur les plus-values, en une page\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#website\",\"url\":\"https:\\\/\\\/www.costmasters.com\\\/\",\"name\":\"Costmasters\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.costmasters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#organization\",\"name\":\"Costmasters\",\"url\":\"https:\\\/\\\/www.costmasters.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.costmasters.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-logo-costmasters_word-1.png\",\"contentUrl\":\"https:\\\/\\\/www.costmasters.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-logo-costmasters_word-1.png\",\"width\":114,\"height\":55,\"caption\":\"Costmasters\"},\"image\":{\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.costmasters.com\\\/#\\\/schema\\\/person\\\/3cf1b4cd7352824684853dac4ed7d30a\",\"name\":\"Charles Markowicz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b41bbaaee2450d72b5e4c42f393e274bb860da649de0c9798d4049a3a7d0642?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b41bbaaee2450d72b5e4c42f393e274bb860da649de0c9798d4049a3a7d0642?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b41bbaaee2450d72b5e4c42f393e274bb860da649de0c9798d4049a3a7d0642?s=96&d=mm&r=g\",\"caption\":\"Charles Markowicz\"},\"url\":\"https:\\\/\\\/www.costmasters.com\\\/en\\\/author\\\/chmcostmasters-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La synth\u00e8se de la taxe sur les plus-values, en une page - Costmasters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.costmasters.com\/en\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/","og_locale":"en_US","og_type":"article","og_title":"La synth\u00e8se de la taxe sur les plus-values, en une page - Costmasters","og_description":"Il n\u2019y a plus de doute, l\u2019Etat belge taxe d\u00e9sormais les plus-values financi\u00e8res, sous r\u00e9serve des recours introduits contre la loi du 6 avril dernier. Les principes et modalit\u00e9s semblent limpides pour les plus-values sur actions cot\u00e9es. Mais il n\u2019en va pas de m\u00eame pour les participations substantielles des actionnaires et dirigeants de PME. C\u2019est ... Read more","og_url":"https:\/\/www.costmasters.com\/en\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/","og_site_name":"Costmasters","article_published_time":"2026-05-21T11:37:31+00:00","article_modified_time":"2026-05-21T11:37:32+00:00","og_image":[{"width":452,"height":362,"url":"https:\/\/www.costmasters.com\/wp-content\/uploads\/2023\/04\/billets-reduit.jpg","type":"image\/jpeg"}],"author":"Charles Markowicz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Charles Markowicz","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/#article","isPartOf":{"@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/"},"author":{"name":"Charles Markowicz","@id":"https:\/\/www.costmasters.com\/#\/schema\/person\/3cf1b4cd7352824684853dac4ed7d30a"},"headline":"La synth\u00e8se de la taxe sur les plus-values, en une page","datePublished":"2026-05-21T11:37:31+00:00","dateModified":"2026-05-21T11:37:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/"},"wordCount":109,"publisher":{"@id":"https:\/\/www.costmasters.com\/#organization"},"image":{"@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costmasters.com\/wp-content\/uploads\/2023\/04\/billets-reduit.jpg","keywords":["Fiscalit\u00e9"],"articleSection":["Article"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/","url":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/","name":"La synth\u00e8se de la taxe sur les plus-values, en une page - Costmasters","isPartOf":{"@id":"https:\/\/www.costmasters.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/#primaryimage"},"image":{"@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/#primaryimage"},"thumbnailUrl":"https:\/\/www.costmasters.com\/wp-content\/uploads\/2023\/04\/billets-reduit.jpg","datePublished":"2026-05-21T11:37:31+00:00","dateModified":"2026-05-21T11:37:32+00:00","breadcrumb":{"@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/#primaryimage","url":"https:\/\/www.costmasters.com\/wp-content\/uploads\/2023\/04\/billets-reduit.jpg","contentUrl":"https:\/\/www.costmasters.com\/wp-content\/uploads\/2023\/04\/billets-reduit.jpg","width":452,"height":362,"caption":"d\u00e9penser moins - Shutterstock"},{"@type":"BreadcrumbList","@id":"https:\/\/www.costmasters.com\/la-synthese-de-la-taxe-sur-les-plus-values-en-une-page\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.costmasters.com\/"},{"@type":"ListItem","position":2,"name":"La synth\u00e8se de la taxe sur les plus-values, en une page"}]},{"@type":"WebSite","@id":"https:\/\/www.costmasters.com\/#website","url":"https:\/\/www.costmasters.com\/","name":"Costmasters story","description":"","publisher":{"@id":"https:\/\/www.costmasters.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.costmasters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.costmasters.com\/#organization","name":"Costmasters story","url":"https:\/\/www.costmasters.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.costmasters.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.costmasters.com\/wp-content\/uploads\/2021\/04\/cropped-logo-costmasters_word-1.png","contentUrl":"https:\/\/www.costmasters.com\/wp-content\/uploads\/2021\/04\/cropped-logo-costmasters_word-1.png","width":114,"height":55,"caption":"Costmasters"},"image":{"@id":"https:\/\/www.costmasters.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.costmasters.com\/#\/schema\/person\/3cf1b4cd7352824684853dac4ed7d30a","name":"Charles Markowicz","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5b41bbaaee2450d72b5e4c42f393e274bb860da649de0c9798d4049a3a7d0642?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b41bbaaee2450d72b5e4c42f393e274bb860da649de0c9798d4049a3a7d0642?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b41bbaaee2450d72b5e4c42f393e274bb860da649de0c9798d4049a3a7d0642?s=96&d=mm&r=g","caption":"Charles Markowicz"},"url":"https:\/\/www.costmasters.com\/en\/author\/chmcostmasters-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/posts\/3404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/comments?post=3404"}],"version-history":[{"count":2,"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/posts\/3404\/revisions"}],"predecessor-version":[{"id":3407,"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/posts\/3404\/revisions\/3407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/media\/3097"}],"wp:attachment":[{"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/media?parent=3404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/categories?post=3404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costmasters.com\/en\/wp-json\/wp\/v2\/tags?post=3404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}